{"id":851,"date":"2023-08-31T15:49:31","date_gmt":"2023-08-31T13:49:31","guid":{"rendered":"https:\/\/planasailing.com\/?page_id=851"},"modified":"2023-09-01T14:07:53","modified_gmt":"2023-09-01T12:07:53","slug":"link-utili","status":"publish","type":"page","link":"https:\/\/planasailing.com\/index.php\/home\/link-utili\/","title":{"rendered":"link utili"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-theme-palette-6-color has-text-color has-small-font-size wp-block-paragraph\"><!-- Beginning of Link Library Output --><div id='linklist1' class='linklist'><!-- Div Linklist -->\n<div class=\"LinkLibraryCat LinkLibraryCat12 level0\"><!-- Div Category --><div id=\"agonistica\"><!-- Div Category Name --><div class=\"linklistcatname\"><!-- Div Cat Name --><span class=\"linklistcatclass\">Agonistica<\/span><\/div><!-- DivOrHeader --><\/div><!-- Div Category Name -->\n\t<table class='linklisttable'>\n<tr><td style='width:100px'><a href=\"https:\/\/www.ottavazona.org\/it\/I-Campionato-Autunnale-Citt%C3%A0-di-Bari---XXXVI-Trofeo-C.-Bottiglieri---1%5E-giornata_reg849.html\" id=\"link-983\" class=\"track_this_link \" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/11\/VIII-Zona.png\" alt=\"\"\/><\/a><\/td><td><a href=\"https:\/\/www.ottavazona.org\/it\/I-Campionato-Autunnale-Citt%C3%A0-di-Bari---XXXVI-Trofeo-C.-Bottiglieri---1%5E-giornata_reg849.html\" id=\"link-983\" class=\"track_this_link \" rel=\"noopener noreferrer\" target=\"_blank\"><\/a><br \/>\nPortale web del Comitato VIII Zona della Federazione Italiana Vela<br \/>\n<\/tr>\t<\/table>\n<\/div><!-- Div End Category -->\n<div class=\"LinkLibraryCat LinkLibraryCat11 level0\"><!-- Div Category --><div id=\"avvisi\"><!-- Div Category Name --><div class=\"linklistcatname\"><!-- Div Cat Name --><span class=\"linklistcatclass\">Avvisi<\/span><\/div><!-- DivOrHeader --><\/div><!-- Div Category Name -->\n\t<table class='linklisttable'>\n<tr><td style='width:100px'><a href=\"https:\/\/www.guardiacostiera.gov.it\/bari\/Pages\/ordinanze.aspx\" id=\"link-981\" class=\"track_this_link \" rel=\"noopener noreferrer\" title=\"Guardia Costiera Bari &#8211; Ordinanze e Avvisi\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/11\/Guardia-Costiera-BARI.png\" alt=\"Guardia Costiera Bari &#8211; Ordinanze e Avvisi\" title=\"Guardia Costiera Bari &#8211; Ordinanze e Avvisi\"\/><\/a><\/td><td><a href=\"https:\/\/www.guardiacostiera.gov.it\/bari\/Pages\/ordinanze.aspx\" id=\"link-981\" class=\"track_this_link \" rel=\"noopener noreferrer\" target=\"_blank\">Guardia Costiera Bari &#8211; Ordinanze e Avvisi<\/a><br \/>\n<br \/>\n<\/tr>\t<\/table>\n<\/div><!-- Div End Category -->\n<div class=\"LinkLibraryCat LinkLibraryCat8 level0\"><!-- Div Category --><div id=\"formazione\"><!-- Div Category Name --><div class=\"linklistcatname\"><!-- Div Cat Name --><span class=\"linklistcatclass\">Formazione<\/span><\/div><!-- DivOrHeader --><\/div><!-- Div Category Name -->\n\t<table class='linklisttable'>\n<tr><td style='width:100px'><a href=\"http:\/\/www.lucasabiu.com\" id=\"link-843\" class=\"track_this_link \" rel=\"noopener noreferrer\" title=\"Luca Sabiu\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/lucasabiu.com\/wp-content\/uploads\/2022\/11\/00DC1DA9-A23E-4FAE-B60E-17427AE7FB9F-1-scaled.jpeg\" alt=\"Luca Sabiu\" title=\"Luca Sabiu\"\/><\/a><\/td><td><a href=\"http:\/\/www.lucasabiu.com\" id=\"link-843\" class=\"track_this_link \" rel=\"noopener noreferrer\" target=\"_blank\">Luca Sabiu<\/a><br \/>\nIstruttore federale FIV, UISP e Tutor per la Federazione Italiana Vela, con una personale didattica da Sailing Coach con un lavoro One2One sull\u2019allievo, incentrato sull\u2019approccio mentale e la gestione dello stress a bordo; diciamo che mi piace lavorare sull\u2019autonomia del velista. Formatore Istruttori Altura per le pi\u00f9 importanti realt\u00e0 nazionali a bordo del mio Class 40 Flow: la mia \u201cbarca laboratorio\u201d.<br \/>\n<\/tr>\t<\/table>\n<\/div><!-- Div End Category -->\n<div class=\"LinkLibraryCat LinkLibraryCat10 level0\"><!-- Div Category --><div id=\"previsioni-meteo\"><!-- Div Category Name --><div class=\"linklistcatname\"><!-- Div Cat Name --><span class=\"linklistcatclass\">Previsioni meteo<\/span><\/div><!-- DivOrHeader --><\/div><!-- Div Category Name -->\n\t<table class='linklisttable'>\n<tr><td style='width:100px'><a href=\"#\" id=\"link-977\" class=\"track_this_link \" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/11\/meto-Greece.png\" alt=\"\"\/><\/a><\/td><td><br \/>\nWeather Forecast - Atmospheric Modeling and Weather Forecasting Group - Athens University - Greece Area<br \/>\n<td style='width:100px'><a href=\"https:\/\/www.meteoam.it\/it\/avviso-burrasca\" id=\"link-979\" class=\"track_this_link \" rel=\"noopener noreferrer\" title=\"Avvisi di burrasca e bollettini Meteomar &#8211; Aeronautica Militare\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/11\/Aeronautica-Militare.png\" alt=\"Avvisi di burrasca e bollettini Meteomar &#8211; Aeronautica Militare\" title=\"Avvisi di burrasca e bollettini Meteomar &#8211; Aeronautica Militare\"\/><\/a><\/td><td><a href=\"https:\/\/www.meteoam.it\/it\/avviso-burrasca\" id=\"link-979\" class=\"track_this_link \" rel=\"noopener noreferrer\" target=\"_blank\">Avvisi di burrasca e bollettini Meteomar &#8211; Aeronautica Militare<\/a><br \/>\nStato Maggiore Aeronautica Militare - Ufficio Aviazione Generale e Meteorologia Centro Nazionale di Meteorologia e Climatologia Aerospaziale Centro Tecnico per la Meteorologia Centro Aeronautica Militare di Montagna Comando della Squadra Aerea \u2013 Ufficio per la Meteorologia Ufficio meteorologico del Comando Operazioni aeree<br \/>\n<\/tr><tr><td style='width:100px'><a href=\"https:\/\/www.lamma.toscana.it\/mare\/modelli\/vento-mare.php\" id=\"link-970\" class=\"track_this_link \" rel=\"noopener noreferrer\" title=\"Forecast\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/11\/wind10.AA_.2.png\" alt=\"Forecast\" title=\"Forecast\"\/><\/a><\/td><td><a href=\"https:\/\/www.lamma.toscana.it\/mare\/modelli\/vento-mare.php\" id=\"link-970\" class=\"track_this_link \" rel=\"noopener noreferrer\" target=\"_blank\">Forecast<\/a><br \/>\nConsorzio LAMMA Toscana - Previsioni Meteo<br \/>\n<td style='width:100px'><a href=\"https:\/\/www.windy.com\/?40.648,16.862,8\" id=\"link-974\" class=\"track_this_link \" rel=\"noopener noreferrer\" title=\"Windy\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/11\/windy-img.png\" alt=\"Windy\" title=\"Windy\"\/><\/a><\/td><td><a href=\"https:\/\/www.windy.com\/?40.648,16.862,8\" id=\"link-974\" class=\"track_this_link \" rel=\"noopener noreferrer\" target=\"_blank\">Windy<\/a><br \/>\nCaratteristiche di Windy: \u2022 Previsioni del vento globali per i prossimi 10 giorni con intervalli da 1 a 3 ore \u2022 Mappa interattiva del vento - puoi vedere sulla mappa da dove soffia il vento \u2022 Maree, onde \u2022<br \/>\n<\/tr>\t<\/table>\n<\/div><!-- Div End Category -->\n<script type='text\/javascript'>\njQuery(document).ready(function()\n{\njQuery('.arrow-up').hide();\njQuery('#linklist1 a.track_this_link').click(function() {\nlinkid = this.id;\nlinkid = linkid.substring(5);\npath = '';\njQuery.ajax( {    type: 'POST',    url: 'https:\/\/planasailing.com\/wp-admin\/admin-ajax.php',     data: { action: 'link_library_tracker',             _ajax_nonce: '2caf4b4203',             id:linkid, xpath:path }     });\nreturn true;\n});\njQuery('#linklist1 .expandlinks').click(function() {\ntarget = '.' + jQuery(this).attr('id');\nsubcattarget = '.' + jQuery(this).attr('data-subcat');\nif ( jQuery( target ).is(':visible') ) {\njQuery(target).slideUp();\njQuery(subcattarget).slideToggle();\njQuery(this).children('img').attr('src', 'https:\/\/planasailing.com\/wp-content\/plugins\/link-library\/icons\/expand-32.png');\n} else {\njQuery(target).slideDown();\njQuery(subcattarget).slideToggle();\njQuery(this).children('img').attr('src', 'https:\/\/planasailing.com\/wp-content\/plugins\/link-library\/icons\/collapse-32.png');\n}\n});\njQuery('#linklist1 .linklistcatclass').click(function() {\njQuery(this).siblings('.expandlinks').click();\n});\njQuery('#linklist1 .linklistcatnamedesc').click(function() {\njQuery(this).siblings('.expandlinks').click();\n});\n});\n<\/script>\n<\/div><!-- Div Linklist -->\n<!-- End of Link Library Output -->\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":2,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-851","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>link utili - planasailing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/planasailing.com\/index.php\/home\/link-utili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"link utili - planasailing\" \/>\n<meta property=\"og:url\" content=\"https:\/\/planasailing.com\/index.php\/home\/link-utili\/\" \/>\n<meta property=\"og:site_name\" content=\"planasailing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/planasailing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-01T12:07:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/home\\\/link-utili\\\/\",\"url\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/home\\\/link-utili\\\/\",\"name\":\"link utili - planasailing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/#website\"},\"datePublished\":\"2023-08-31T13:49:31+00:00\",\"dateModified\":\"2023-09-01T12:07:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/home\\\/link-utili\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/planasailing.com\\\/index.php\\\/home\\\/link-utili\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/home\\\/link-utili\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/planasailing.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/planasailing.com\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"link utili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/#website\",\"url\":\"https:\\\/\\\/planasailing.com\\\/\",\"name\":\"planasailing\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/planasailing.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/#organization\",\"name\":\"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L.\",\"url\":\"https:\\\/\\\/planasailing.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-9da7b-logo_plana_sailing.jpeg\",\"contentUrl\":\"https:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-9da7b-logo_plana_sailing.jpeg\",\"width\":512,\"height\":204,\"caption\":\"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/planasailing\\\/\",\"https:\\\/\\\/www.instagram.com\\\/planasailing\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"link utili - planasailing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/planasailing.com\/index.php\/home\/link-utili\/","og_locale":"it_IT","og_type":"article","og_title":"link utili - planasailing","og_url":"https:\/\/planasailing.com\/index.php\/home\/link-utili\/","og_site_name":"planasailing","article_publisher":"https:\/\/www.facebook.com\/planasailing\/","article_modified_time":"2023-09-01T12:07:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/planasailing.com\/index.php\/home\/link-utili\/","url":"https:\/\/planasailing.com\/index.php\/home\/link-utili\/","name":"link utili - planasailing","isPartOf":{"@id":"https:\/\/planasailing.com\/#website"},"datePublished":"2023-08-31T13:49:31+00:00","dateModified":"2023-09-01T12:07:53+00:00","breadcrumb":{"@id":"https:\/\/planasailing.com\/index.php\/home\/link-utili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/planasailing.com\/index.php\/home\/link-utili\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/planasailing.com\/index.php\/home\/link-utili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/planasailing.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/planasailing.com\/"},{"@type":"ListItem","position":3,"name":"link utili"}]},{"@type":"WebSite","@id":"https:\/\/planasailing.com\/#website","url":"https:\/\/planasailing.com\/","name":"planasailing","description":"","publisher":{"@id":"https:\/\/planasailing.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/planasailing.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/planasailing.com\/#organization","name":"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L.","url":"https:\/\/planasailing.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/planasailing.com\/#\/schema\/logo\/image\/","url":"https:\/\/planasailing.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-9da7b-logo_plana_sailing.jpeg","contentUrl":"https:\/\/planasailing.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-9da7b-logo_plana_sailing.jpeg","width":512,"height":204,"caption":"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L."},"image":{"@id":"https:\/\/planasailing.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/planasailing\/","https:\/\/www.instagram.com\/planasailing\/"]}]}},"_links":{"self":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages\/851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/comments?post=851"}],"version-history":[{"count":8,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages\/851\/revisions"}],"predecessor-version":[{"id":876,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages\/851\/revisions\/876"}],"up":[{"embeddable":true,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages\/2"}],"wp:attachment":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/media?parent=851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}