{"id":751,"date":"2023-08-28T10:26:29","date_gmt":"2023-08-28T08:26:29","guid":{"rendered":"https:\/\/planasailing.com\/?page_id=751"},"modified":"2023-08-28T12:48:07","modified_gmt":"2023-08-28T10:48:07","slug":"diario-di-bordo-flow-clinic-week-2023","status":"publish","type":"page","link":"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/","title":{"rendered":"Diario di bordo FLOW Clinic Week 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image alignfull size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"485\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina-1024x485.jpg\" alt=\"\" class=\"wp-image-755\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina-1024x485.jpg 1024w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina-300x142.jpg 300w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina-768x364.jpg 768w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina-1536x728.jpg 1536w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina.jpg 1599w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-pullquote has-small-font-size\"><blockquote><p>Flow per noi \u00e8 stata una conquista: dapprima avevamo occhi solo per le sue performance che ci hanno impressionati gi\u00e0 al primo incontro, poi siamo passati ad ascoltare i suoi rumori, drizze e scotte che lavorano e non cedono, la prua che sbatte e il vento che sibila tra le sartie ed infine a percepirla restando con lei nel suo flow (diario di bordo, giorno 5)<\/p><\/blockquote><\/figure>\n\n\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"568\" height=\"568\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine2.jpg\" alt=\"\" class=\"wp-image-756 size-full\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine2.jpg 568w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine2-300x300.jpg 300w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine2-150x150.jpg 150w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Giorno 1, 20-08-23<\/p><\/blockquote><\/figure>\n<\/div><\/div>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Un buongiorno da bordo di FLOW. Floriana, Martino, Donatello e Fabrizio della scuola Plana Sailing formeranno a partire da oggi l\u2019equipaggio di FLOW insieme al comandante navi Luca Sabiu e il suo vice di bordo Roberto. Ieri sera dopo gli onori di casa da parte del comandante, una cena nei vicoli di Cagliari ci ha permesso di rompere il ghiaccio. Questa mattina, cercando di sfruttare un po&#8217; di aria pi\u00f9 mite, sessione di lavoro a terra per conoscere FLOW. Si parte con la descrizione da parte di Luca delle dotazioni di bordo presenti sottocoperta, quelle di sicurezza che sono predisposte nei punti ove servono, perch\u00e9 quando ne \u201cavrete bisogno in mare in condizioni di emergenza dovete sapere cosa vi occorre e dove recuperarlo\u201d. Quindi annotiamo la posizione di tutto, dai tappi rigorosamente presenti ciascuno nelle possibili e presumibili vie d\u2019acqua in corrispondenza delle prese a mare, alla farmacia di bordo, una valigetta rossa che riporta sul dorso il numero di telefono del CIRM da contattare in caso di chiamata d&#8217;emergenza e le necessarie le informazioni da fornire che \u00e8 organizzata minuziosamente con contenitori e scritte che indicano per categoria di malore i farmaci disponibili, fino al bidone survie dove Luca ripone Vhf portatile, piccole luci di emergenza, un Gps portatile, fuochi e razzi di segnalazione che l\u2019incaricato deve portare a bordo della zattera di salvataggio. A ciascun membro dell\u2019equipaggio di FLOW a bordo viene assegnata la sua cuccetta; la brandina identifica con la propria sacca stagna che contiene la propria gamella, tazza e cucchiaio, un nome per ciascuno dei 5 membri dell\u2019equipaggio: Bolina, Traverso, Poppa, Lasco e Spi. Assegnare a ciascuno un nome non \u00e8 coreografia, ma ha uno scopo ben preciso: per il piano di abbandono imbarcazione a ciascuno viene affidato il compito di prelevare e portare a bordo della zattera dotazioni e beni che sono essenziali per la permanenza a bordo del mezzo di emergenza che dovr\u00e0 essere auspicabilmente \u201cla pi\u00f9 breve possibile, ma con le migliori condizioni possibili\u201d.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:52% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"581\" height=\"292\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine3.jpg\" alt=\"\" class=\"wp-image-757 size-full\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine3.jpg 581w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine3-300x151.jpg 300w\" sizes=\"auto, (max-width: 581px) 100vw, 581px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Il caldo si fa sentire. Andiamo a pranzo e durante il pranzo Luca ci mostra e ci fa lavorare con previsioni meteo e routage per stabilire nella settimana la rotta migliore in direzione Marettimo. Gi\u00e0 da subito, l\u2019analisi delle condizioni del vento mostra un buon vento nei primi due giorni che fuori dal Golfo di Cagliari dovrebbe mettersi da nord. Tuttavia, preoccupa gi\u00e0 un buco di vento, una enorme \u201cbolla\u201d di assenza di vento che si formerebbe tra un paio di giorni sul mar Tirreno, al centro tra la punta sud est della Sardegna e la Sicilia, cio\u00e8 proprio dove navigheremo in rientro a Cagliari.<br><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignfull is-stacked-on-mobile\" style=\"grid-template-columns:52% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"305\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine4.jpg\" alt=\"\" class=\"wp-image-758 size-full\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine4.jpg 643w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine4-300x142.jpg 300w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Dopo il pranzo a terra, passiamo quindi alle manovre e armo di FLOW. La complessit\u00e0 aumenta: armo vele con solent e randa, trinca, code 0 e vari spi sottocoperta per varie condizioni di vento.<br>Tutto chiaro? Non proprio, ma confidiamo, guidati da Luca e Roberto, di riuscire presto a famigliarizzare con FLOW.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Rapido check, e si salpa!<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Subito FLOW mostra le sue doti, bolina con 9 nodi di velocit\u00e0. Noi sopravento guardiamo ammirati la scia montante dietro la poppa di FLOW. Subito Luca fa un giro di timone per tutti e nel frattempo organizza i turni che partono alle 19.00 con rotazione a coppie di tre ore. Inizia a calare il sole e Luca prepara la cena, un pasto caldo, mostrando per i prossimi giorni le tecniche di cottura con pentola a pressione con scarsit\u00e0 di risorse, acqua e gas, dunque da risparmiare il pi\u00f9 possibile. Si naviga al lasco, dopocena, con tramonto, ma il mare inizia a formarsi con una fastidiosa onda lunga. L\u2019inizio della lunga tratta di 120 mn non \u00e8 dei migliori. Alcuni di noi manifestano presto problemi di mal di mare. Cala il buio e ci si avvicenda con i turni di tre ore.<br><br>La prima notte di navigazione per condizioni di mare e vento non \u00e8 del tutto facile, essendo per tutti noi anche la prima notte in navigazione d\u2019altura.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"1024\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine5-1-769x1024.jpg\" alt=\"\" class=\"wp-image-761\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine5-1-769x1024.jpg 769w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine5-1-225x300.jpg 225w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine5-1-768x1023.jpg 768w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine5-1.jpg 906w\" sizes=\"auto, (max-width: 769px) 100vw, 769px\" \/><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Giorno 2, 21-08-23<\/p><\/blockquote><\/figure>\n\n\n\n<div class=\"wp-block-media-text alignfull is-stacked-on-mobile\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"299\" height=\"632\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine6.jpg\" alt=\"\" class=\"wp-image-762 size-full\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine6.jpg 299w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine6-142x300.jpg 142w\" sizes=\"auto, (max-width: 299px) 100vw, 299px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Albeggia. La notte \u00e8 trascorsa ma non nascondiamo le nostre difficolt\u00e0. Tra malori e turni di riposo e guardia non ancora rodati tra noi, la navigazione in mezzo al Mar Tirreno prosegue. Luca l\u2019aveva annunciato ieri: le prime 36\/48 ore per un equipaggio che affronta per la prima volta navigazione di altura, turni di notte con riposo e guardie, non \u00e8 facile.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Almeno la buona notizia \u00e8 che la fastidiosa onda di notte pian piano \u00e8 sparita. La giornata di navigazione prevede ancora alcune ore per arrivare a Marettimo dove si prevede di fare base un giorno e poi rientrare.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">A met\u00e0 mattina Luca e Roberto ci chiamano a raccolta per un briefing importante.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Ci spiegano che le previsioni sul vento per il primo giorno di navigazione sono state abbastanza rispettate, ma che la bolla di assenza di vento sembra anticipare la sua comparsa sulla nostra rotta di rientro al termine, gi\u00e0 presentandosi al termine della giornata di oggi. Questo potrebbe costringerci dal mercoled\u00ec una lunga e faticosa risalita verso Cagliari con buona parte \u2013 se non tutta \u2013 della rotta coperta a motore.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Capito il problema, decidiamo tutti all\u2019unanimit\u00e0 di non raggiungere pi\u00f9 Marettimo ma di procedere qualche miglio avanti e girare anticipando di un giorno il rientro verso la Sardegna. Luca propone di continuare la navigazione della settimana in zone pi\u00f9 sicure al riparo di cali di vento che ci lascerebbero in braghe di tela in mezzo al Tirreno.<\/p>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"305\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine7-1.jpg\" alt=\"\" class=\"wp-image-791\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine7-1.jpg 643w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine7-1-300x142.jpg 300w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/figure>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Giriamo FLOW e ripuntiamo sulla costa SE della Sardegna. Siamo in navigazione da circa 15 ore.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Arriva ora di cena. La situazione a bordo con malori, piuttosto che migliorare, \u00e8 peggiorata. Affrontiamo il turno di notte con la turnazione modificata e cercando di dare riposo ogni tanto a chi \u00e8 in grado di stare in coperta. \u00c8 notte e c\u2019\u00e8 una bella stellata sopra le vele di flow che si confondono nel buio ma sono illuminate da strisce fluorescenti nella steccatura del solent che fanno grande compagnia. Ci alterniamo in tre al timone senza riuscire granch\u00e9 a riposare. Ma presto siamo ripagati; si vede la costa. <\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Puntiamo su Villasimius. Ancora 10 mn e ci siamo. Sono le 4 di mattina. Dopo circa mezzora, come da previsioni, il vento ci molla completamente. Luca in pozzetto aspetta paziente per capire se ce n&#8217;\u00e8 ancora per l\u2019atterraggio. Nulla; dopo dieci minuti passati a girare in tondo, accendiamo motore. <br><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Albeggia mentre entriamo in porto; l\u2019equipaggio di FLOW si sveglia. Oggi colazione a terra.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Giorno 3, 22-08-23<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Caff\u00e8 espresso, cappuccini, brioche, spremuta d\u2019arancia. Piaceri della vita di terra.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Quest\u2019oggi rimarremo in porto, abbiamo probabilmente necessit\u00e0 di rifiatare, soprattutto permettere all\u2019equipaggio di riprendere il proprio equilibrio fisico. Parliamo tra noi nella giornata che scorre calda e lenta, cercando dopo pranzo un posto fresco dove riposare. Oggi sottocoperta fermi in porto fa troppo caldo.<br><br>Parliamo tra noi e con Luca e Roberto. Soprattutto delle difficolt\u00e0 incontrate nella navigazione di due giorni non-stop precedenti. Comunque, una media di tutto rispetto con circa 240 mn coperte da Cagliari al punto di inversione rotta a circa 20 mn da Marettimo, fino a Villasimius. Nel frattempo, la situazione malori di bordo \u00e8 migliorata notevolmente. Dopo l\u2019aperitivo a terra decidiamo di cenare a bordo. <br><br>Ci iniziamo a conoscere meglio e a raccontarci un po&#8217;. Roberto mette su musica jazz molto apprezzata. Una bella serata. <br>Oggi niente flow, piuttosto siamo in modalit\u00e0 molto \u201cslow\u201d, ma percepiamo che ci fa bene anche ridurre i ritmi. Una buonanotte da bordo di FLOW.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"305\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine8-1.jpg\" alt=\"\" class=\"wp-image-790\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine8-1.jpg 643w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine8-1-300x142.jpg 300w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Giorno 4, 23-08-23<\/p><\/blockquote><\/figure>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"857\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine9.jpg\" alt=\"\" class=\"wp-image-765 size-full\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine9.jpg 643w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine9-225x300.jpg 225w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Sveglia buona per l\u2019equipaggio di FLOW. Ore 7.30 le sveglie suonano, il comandante da il buongiorno a tutti e scandisce i tempi per salpare. Colazione in porto Villasimius. A seguire, Luca e Roberto aprono una minisessione pratica di disormeggio. Tocca a Donatello mettere subito in pratica. Motore in marcia, prua sopravvento e sfila senza problemi con manovra da navigatore in solitaria. Non pu\u00f2 essere diversamente una lezione di Luca: \u201cpensatevi sempre in navigazione solitaria\u201d. Metodo e procedura e si sta lontano dai problemi anche in condizioni difficili. Ci rimane un messaggio ben chiaro: \u201cl\u2019obiettivo \u00e8 per tutti voi non portarsi il problema in casa!\u201d. Questo lo pensiamo noi di Plana come un regalo prezioso da portarsi a casa. Luca predispone gi\u00e0 FLOW per Code 0 e Solent, via la trinchetta dei primi giorni che pare proprio non essere necessaria per la navigazione di oggi. Con un po&#8217; di motore ci allontaniamo dalla costa per raggiungere i flussi di vento che la pianificazione della mattina ci ha consigliato. Flow corre, anche se la pressione non \u00e8 molta oggi. Mentre raggiungiamo una zona d\u2019aria pi\u00f9 a largo, chiediamo a Luca una sessione applicata di ormeggio e disormeggio in varie situazioni di vento. Agganciato il flusso d\u2019aria a largo, impostiamo rotta vera 250\u00b0 per dirigersi Capo Teulada. Navighiamo nella prima parte di rotta di bolina larga, media di 7 nodi Vp con 7,5-8 nodi di vento. Grande FLOW, \u00e8 una barca che stiamo conoscendo e lei si fa conoscere. Iniziamo a prendere confidenza tra noi e lei: le nostre ore di navigazione trascorrono senza accorgerci e gi\u00e0 sono le due di pomeriggio perci\u00f2 decidiamo di mettere la cambusa in attivit\u00e0. Vento da un po&#8217; di scarso; per passare il Capo, dobbiamo ammainare il Code 0 e passare al Solent. <\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Turnazione al timone, Donatello, Fabrizio, Floriana e Martino devono far camminare FLOW, senza concedere acqua alla bolina. Bella sfida, lavorando di timone sotto raffica per far risalire un po&#8217; la prua. Riusciamo a risalire bene fino a Torre del Coltellazzo. Nonostante l\u2019impegno, sotto costa il vento da le consegne: dobbiamo iniziare a bordeggiare per tenere rotta verso Porto Teulada. Dovendo bordeggiare, poggiamo quanto basta per recuperare velocit\u00e0, 11 nodi di vento FLOW non vuole sprecarli, procediamo con 7,5-8 nodi di velocit\u00e0. Ore 19.00, vediamo l\u2019ingresso del porticciolo. Il comandante saluta in VHF al nostro arrivo, chiedendo indicazioni per un ormeggio, sottovento se disponibile. Ore 19.40, ormeggio completato. Tocca pagare la scommessa, Roby aveva puntato giusto. Docce e in barca a preparare la cena. Stasera piatto cucinato e caldo. Riassetto e riposo, ultime parti della giornata.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"482\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine10.jpg\" alt=\"\" class=\"wp-image-766\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine10.jpg 643w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine10-300x225.jpg 300w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"482\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine11.jpg\" alt=\"\" class=\"wp-image-767\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine11.jpg 643w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine11-300x225.jpg 300w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"304\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine12-2.jpg\" alt=\"\" class=\"wp-image-789\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine12-2.jpg 643w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine12-2-300x142.jpg 300w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Giorno 5, 24-08-23<\/p><\/blockquote><\/figure>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"857\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine13.jpg\" alt=\"\" class=\"wp-image-770 size-full\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine13.jpg 643w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine13-225x300.jpg 225w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Nuovo giorno a bordo di FLOW ed ultimo di navigazione. Sveglia solita da barca in porto, ore 7.30. Colazione insieme e poi si inizia con alcune pillole di esperienza per disormeggiare in banchina in condizioni un po&#8217; antipatiche, con vento quasi in prua che, anche se non sostenuto, pu\u00f2 creare difficolt\u00e0 con continui salti a dritta e a sinistra per trovare il giusto tonneggio sopravento della prua, pronti poi a liberarsi dalle cime di ormeggio.<br>Partiti alla 10.30 con qualche problema in disormeggio \u2013 si dovr\u00e0 fare esperienza per poter tradurre schema e procedura in propri automatismi da buon marinaio \u2013 si procede da Capo Teulada in direzione NW a risalire la costa Ovest della Sardegna, puntando verso l\u2019Isola di San Pietro con andatura di bolina e 17 nodi di vento apparente. Prevenendo, ad issata randa in uscita dal porticciolo, Luca ci indica l\u2019importanza di prevenire ogni problema e senza rimandare a dopo, prendiamo una mano di terzaroli e Solent a prua. Dopo i primi giorni, ormai a bordo iniziamo a prendere consapevolezza di quanto fondamentale sia poter avere una visione generale da buon marinaio della situazione, anche gi\u00e0 prima di avere iniziato qualsiasi manovra di disormeggio. Luca ci aiuta a guardare dalla banchina sia intorno a noi, sia a largo: quante barche stanno prendendo una mano di terzaroli una volta velate con non poche difficolt\u00e0: bella sensazione quella di realizzare che \u00e8 possibile assimilare un nuovo approccio alla navigazione in sicurezza: \u201ccostruitevi un metodo, anche fatto vostro, che risolva la situazione, partendo da uno che funziona\u201d.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Risaliamo fino all\u2019isolotto del Toro, decidiamo di non proseguire fino all\u2019Isola di San Pietro poich\u00e9 la situazione sta cambiando, con rinforzo di vento che troveremo a breve nella discesa verso SE per rientrare alla base, Cagliari.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Giriamo intorno all\u2019isola del Toro e ci portiamo di bolina per bordeggiare e tenere rotta circa SE.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Il vento presto rinforza come osservato in lontananza su alcuni movimenti di riduzione velatura a bordo di altre barche sull\u2019altro bordo.&nbsp; Rolliamo il Solent, issiamo vela di trinca. Viriamo e ci portiamo di bolina sul nuovo bordo sotto costa. In approccio al capo Teulada, il vento apparente rinforza a 22 nodi. Martino timona bello deciso, barca potente e vento in faccia. Per non perdere troppa acqua sul bordo sotto costa, per doppiare Capo Teulada, decidiamo di virare. La virata viene completata, tutto regolare. Anzi no. Luca si guarda in giro: \u201cragazzi abbiamo un problema da risolvere, guardatevi attorno\u201d. La volante alta sottovento purtroppo non ben cazzata \u00e8 andata sopravento alla randa, impedendo alla randa di passare sulle nuove mure in una nuova virata. Proviamo alcune manovre di disimpegno, lascando quanto pi\u00f9 possibile la volante, ma nulla da fare.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Si ritorna al metodo, basato sulle tecniche gi\u00e0 viste nei giorni scorsi: se la volante non passa perch\u00e9 ostacolata dallo square top della randa, allora uniamo due risultati in uno: gi\u00f9 di randa quanto basta con una seconda mano di terzaroli e proviamo a far passare la volante in virata. Ottimo! Problema risolto in sicurezza.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Viriamo ancora; vento teso. \u00c8 ora di chiudere il Solent e issare vela di trinca. Alla successiva virata, ancora un problema: nel passare sulle altre mura, il meolo della vela di trinca rimane impigliato nella struttura radar. Luca chiede il mezzo marinaio. Comanda una orzata decisa, per puntare la vela togliendo pressione e permettere di disimpegnare il meolo dal radar.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Rimediato, procediamo con il bordo di bolina a velatura ridotta. Altra virata, identico problema, \u201cmai successo prima d\u2019ora e soprattutto strano due volte consecutive\u201d. Eseguiamo un\u2019altra manovra per puntare la vela e con il mezzo marinaio liberiamo nuovamente il meolo della vela di trinca.&nbsp; Decidiamo di ammainare la vela di trinca, ma proprio in fase di ammainata, Donatello e Roberto a prua notano che il punto di mura della vela di trinca era stato erroneamente posizionato pi\u00f9 \u201calto\u201d. Analizzando il problema, capiamo che proprio quei pochi centimetri in allungo della mura causavano un avvicinamento non previsto in armo della velatura di trinca, causando dunque il ripetuto impigliarsi nella struttura radar in fase di virata. Buona cosi, altro problema risolto e soprattutto compresa la causa.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"263\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine14.png\" alt=\"\" class=\"wp-image-771 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Finalmente approcciamo Capo Teulada, il vento cala e si mantiene in apparente di bolina sui 16 nodi, pur sempre una bolina di tutto rispetto. Decidiamo di organizzare il pranzo. Nonostante la bolina stretta, in cambusa si preparano le gamelle per tutti. Caff\u00e8 e si continua a bordeggiare, con vento che riduce.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Ah, dimenticavamo. Mezzora prima Luca e Roberto spiegano a bordo la manovra Quick Stop. Schema in lavagna, descrizione precisa dei passaggi. Passata una mezz\u2019ora, sentiamo Luca gridare: \u201cUomo a mare\u201d! Vediamo l\u2019asta IOR in acqua! Via con la QUICK STOP, recuperiamo in meno di 40 secondi l\u2019uomo, cio\u00e8 l\u2019asta\u2026. Decisamente una lezione di apprendimento pratica\u2026<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Ci portiamo al largo di Capo Spartivento per guadagnare acqua e permetterci di procedere con un bordo soltanto fino all\u2019imboccatura del porto di Cagliari.<\/p>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"361\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine15.jpg\" alt=\"\" class=\"wp-image-772\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine15.jpg 643w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine15-300x168.jpg 300w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Iniziamo a goderci il tramonto in andatura di bolina ma con mare calmo e vento a 8 nodi. Le foto di Donatello parlano da s\u00e9.<br><br>La sensazione a bordo \u00e8 di relax, si chiacchiera tenendo d\u2019occhio gradi bussola e windex per non scadere e rimanere sotto costa senza dover bordeggiare nuovamente da Capo Spartivento. La virata in cappa, primo step della Quick Stop scopriamo anche che \u00e8 non meno utile per una cena di grande relax: barca ferma, Fabrizio, Floriana e Martino preparano per l\u2019equipaggio. Un primo con pasta alla crema di fagioli, rosmarino&nbsp; e acciughe viene apprezzata a bordo. Ci prepariamo al crepuscolo per il lungo bordo di bolina sotto costa. Mare decisamente clemente, calmo, velocit\u00e0 di crociera intorno ai 6,5 nodi con 7,5 nodi di vento apparente. Situazione di comfort che ci fa bene, guardando le stelle e finalmente la prima luna della nostra settimana con il suo riverbero sull\u2019acqua. Luci della costa che si accendono, in compagnia del \u201cflusso\u201d di acqua intorno a FLOW.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Flow per noi \u00e8 stata una conquista: dapprima avevamo occhi solo per le sue performance che ci hanno impressionati gi\u00e0 al primo incontro, poi siamo passati ad ascoltare i suoi rumori, drizze e scotte che lavorano e non cedono, la prua che sbatte e il vento che sibila tra le sartie ed infine a percepirla restando con lei nel suo flow\u2026.luce verde, \u00e8 l\u2019ingresso del porto di Cagliari. Sono le 5 del mattino, da Flow \u00e8 tutto.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Giorno 6, 25-08-23<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:200\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Abbiamo dormito fino al rumore sordo del rimorchiatore che faceva benzina. Buongiorno a tutto l\u2019equipaggio di FLOW.&nbsp; Ore 7.00, colazione a terra al Bar Roma che aperto dalle 4,30 fa da sveglia alla citt\u00e0 di Cagliari. Per ora la mattinata \u00e8 ancora con poca afa, ma si prevede molto caldo gi\u00e0 a met\u00e0 mattinata. Oggi \u00e8 prevista una sessione di debriefing con Luca e Roberto che ci hanno accompagnato per mano in questa nostra esperienza.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:200\"><\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:24% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"429\" height=\"542\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine20-2.jpg\" alt=\"\" class=\"wp-image-780 size-full\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine20-2.jpg 429w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine20-2-237x300.jpg 237w\" sizes=\"auto, (max-width: 429px) 100vw, 429px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Una parte tecnica di analisi e sintesi delle manovre importanti provate ieri e nei giorni precedenti. Si riporta sul taccuino quanto visto. Come e quando riduci le vele, in sicurezza, senza far sbattere le vele.. perch\u00e9 indubbiamente \u00e8 un rumore assordante che il buon marinaio non deve mai far sentire sulla sua barca. Ripassiamo quindi mano di terzaroli, la quick stop, la manovra rapida di recupero uomo a mare, che poi era l\u2019asta IOR lanciata a tradimento da Luca. Come eseguiamo un disormeggio in equipaggio ridotto anche in condizioni difficili di vento da prua. E ancora, come si esegue una chiamata di MayDay, cosa scandire durante la chiamata. Oppure semplicemente, come farsi accogliere per la notte dal porto che si sta raggiungendo.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Il concetto di navigazione in sicurezza \u00e8 diffuso in ogni centimetro di spazio all\u2019interno di FLOW. Facciamo delle foto volentieri sottocoperta alle lavagnette che FLOW&nbsp; impiega per i suoi insegnamenti ai nuovi marinai. Siamo certi che le foto torneranno buone in futuro.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine16-1.jpg\" alt=\"\" class=\"wp-image-776\" style=\"width:426px;height:555px\" width=\"426\" height=\"555\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine16-1.jpg 531w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine16-1-231x300.jpg 231w\" sizes=\"auto, (max-width: 426px) 100vw, 426px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine17.jpg\" alt=\"\" class=\"wp-image-774\" style=\"width:375px;height:551px\" width=\"375\" height=\"551\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine17.jpg 435w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine17-204x300.jpg 204w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine18-1.jpg\" alt=\"\" class=\"wp-image-777\" style=\"width:820px;height:462px\" width=\"820\" height=\"462\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">E poi, il racconto tutto nostro, cio\u00e8 quello su di noi; come eravamo sei giorni fa e come siamo oggi.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Neanche immaginabile al terzo giorno quanti e quali cambiamenti FLOW aveva in serbo per l\u2019equipaggio di Plana Sailing. Luca traccia un quadro per ciascuno raccontandoci che sia lui che Roberto hanno indistintamente osservato per ciascuno un miglioramento e crescita notevole. Non solo di natura tecnica ma, soprattutto, mentale ed emotiva. In realt\u00e0, ciascuno di noi gi\u00e0 da qualche giorno \u00e8 gi\u00e0 consapevole di quanta strada ha percorsa con qualche centinaio di miglia di navigazione. C\u2019\u00e8 chi il primo giorno aveva paura del buio in mare aperto, quando, in assenza di bagliori sull\u2019acqua della luna, l\u2019orizzonte non si distingueva pi\u00f9 e, nonostante il mare formato, si doveva mantenere andatura, con occhio ai gradi bussola e angolo costante al vento. Chi aveva meno consapevolezza delle enormi qualit\u00e0 tecniche acquisite da duro lavoro su Faust, alcune ancora neanche rivelate, e del piacere che porta la navigazione. Chi tra noi ha messo in atto un cambiamento di atteggiamento mentale alla difficolt\u00e0 e fatica fisica impressionante, mostrando in ultimo una forza di reazione e di volont\u00e0 ammirevole. Chi tra noi ha trasformato, quasi in un frullatore di emozioni, il proprio approccio alla navigazione con un nuovo senso di felice responsabilit\u00e0 che la conduzione durante la guardia di notte impone nei confronti del suo equipaggio.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"482\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine21.jpg\" alt=\"\" class=\"wp-image-781\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine21.jpg 643w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine21-300x225.jpg 300w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/figure>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:200\"><\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:34% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"429\" height=\"501\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine22-3.jpg\" alt=\"\" class=\"wp-image-785 size-full\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine22-3.jpg 429w, https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/Immagine22-3-257x300.jpg 257w\" sizes=\"auto, (max-width: 429px) 100vw, 429px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-small-font-size wp-block-paragraph\">Si parla tanto attorno al tavolo. La settimana era iniziata con la comprensione fin da subito da un lato delle enormi doti tecniche di FLOW, che aveva lasciato tutti noi impressionati alla prima bolina verso Marettimo; dall\u2019altro della enorme competenza di Luca costruita in anni di esperienza \u2013 spesso duramente acquisita. <\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Ma oggi dopo appena sei giorni&nbsp; \u2013 sembra incredibile \u2013 passati assieme, FLOW si \u00e8 lasciata conoscere a fondo, nel suo lato pi\u00f9 emozionale. Forse al giorno due aveva gi\u00e0 capito come sarebbe andata a finire e non aspettava l\u2019ora di godersi la scena conclusiva, l\u00ec a pochi metri da noi: giro di mirto del dopocena e occhi lucidi per l\u2019emozione di aver trovato due nuovi compagni di viaggio e amici. <\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Grazie Luca e Roberto. <\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Siamo gi\u00e0 nel \u2026flow\u2026alla prossima!<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Flow per noi \u00e8 stata una conquista: dapprima avevamo occhi solo per le sue performance che ci hanno impressionati gi\u00e0 al primo incontro, poi siamo passati ad ascoltare i suoi&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-751","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diario di bordo FLOW Clinic Week 2023 - planasailing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diario di bordo FLOW Clinic Week 2023 - planasailing\" \/>\n<meta property=\"og:description\" content=\"Flow per noi \u00e8 stata una conquista: dapprima avevamo occhi solo per le sue performance che ci hanno impressionati gi\u00e0 al primo incontro, poi siamo passati ad ascoltare i suoi...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"planasailing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/planasailing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-28T10:48:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina-1024x485.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/diario-di-bordo-flow-clinic-week-2023\\\/\",\"url\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/diario-di-bordo-flow-clinic-week-2023\\\/\",\"name\":\"Diario di bordo FLOW Clinic Week 2023 - planasailing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/diario-di-bordo-flow-clinic-week-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/diario-di-bordo-flow-clinic-week-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/img-copertina-1024x485.jpg\",\"datePublished\":\"2023-08-28T08:26:29+00:00\",\"dateModified\":\"2023-08-28T10:48:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/diario-di-bordo-flow-clinic-week-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/planasailing.com\\\/index.php\\\/diario-di-bordo-flow-clinic-week-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/diario-di-bordo-flow-clinic-week-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/img-copertina.jpg\",\"contentUrl\":\"https:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/img-copertina.jpg\",\"width\":1599,\"height\":758},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/diario-di-bordo-flow-clinic-week-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/planasailing.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diario di bordo FLOW Clinic Week 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/#website\",\"url\":\"https:\\\/\\\/planasailing.com\\\/\",\"name\":\"planasailing\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/planasailing.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/#organization\",\"name\":\"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L.\",\"url\":\"https:\\\/\\\/planasailing.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-9da7b-logo_plana_sailing.jpeg\",\"contentUrl\":\"https:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-9da7b-logo_plana_sailing.jpeg\",\"width\":512,\"height\":204,\"caption\":\"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/planasailing\\\/\",\"https:\\\/\\\/www.instagram.com\\\/planasailing\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diario di bordo FLOW Clinic Week 2023 - planasailing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/","og_locale":"it_IT","og_type":"article","og_title":"Diario di bordo FLOW Clinic Week 2023 - planasailing","og_description":"Flow per noi \u00e8 stata una conquista: dapprima avevamo occhi solo per le sue performance che ci hanno impressionati gi\u00e0 al primo incontro, poi siamo passati ad ascoltare i suoi...","og_url":"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/","og_site_name":"planasailing","article_publisher":"https:\/\/www.facebook.com\/planasailing\/","article_modified_time":"2023-08-28T10:48:07+00:00","og_image":[{"url":"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina-1024x485.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/","url":"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/","name":"Diario di bordo FLOW Clinic Week 2023 - planasailing","isPartOf":{"@id":"https:\/\/planasailing.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/#primaryimage"},"image":{"@id":"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina-1024x485.jpg","datePublished":"2023-08-28T08:26:29+00:00","dateModified":"2023-08-28T10:48:07+00:00","breadcrumb":{"@id":"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/#primaryimage","url":"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina.jpg","contentUrl":"https:\/\/planasailing.com\/wp-content\/uploads\/2023\/08\/img-copertina.jpg","width":1599,"height":758},{"@type":"BreadcrumbList","@id":"https:\/\/planasailing.com\/index.php\/diario-di-bordo-flow-clinic-week-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/planasailing.com\/"},{"@type":"ListItem","position":2,"name":"Diario di bordo FLOW Clinic Week 2023"}]},{"@type":"WebSite","@id":"https:\/\/planasailing.com\/#website","url":"https:\/\/planasailing.com\/","name":"planasailing","description":"","publisher":{"@id":"https:\/\/planasailing.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/planasailing.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/planasailing.com\/#organization","name":"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L.","url":"https:\/\/planasailing.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/planasailing.com\/#\/schema\/logo\/image\/","url":"https:\/\/planasailing.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-9da7b-logo_plana_sailing.jpeg","contentUrl":"https:\/\/planasailing.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-9da7b-logo_plana_sailing.jpeg","width":512,"height":204,"caption":"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L."},"image":{"@id":"https:\/\/planasailing.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/planasailing\/","https:\/\/www.instagram.com\/planasailing\/"]}]}},"_links":{"self":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages\/751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/comments?post=751"}],"version-history":[{"count":15,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages\/751\/revisions"}],"predecessor-version":[{"id":813,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages\/751\/revisions\/813"}],"wp:attachment":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/media?parent=751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}