{"id":391,"date":"2022-08-06T18:28:05","date_gmt":"2022-08-06T16:28:05","guid":{"rendered":"http:\/\/planasailing.com\/?page_id=391"},"modified":"2022-08-08T08:38:32","modified_gmt":"2022-08-08T06:38:32","slug":"info-e-iscrizioni","status":"publish","type":"page","link":"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/","title":{"rendered":"info e iscrizioni"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"1181\" class=\"wp-block-cover__image-background wp-image-392\" alt=\"\" src=\"https:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30.jpg 1181w, https:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30-300x300.jpg 300w, https:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30-1024x1024.jpg 1024w, https:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30-150x150.jpg 150w, https:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30-768x768.jpg 768w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-theme-palette-9-color has-text-color wp-block-paragraph\" style=\"font-size:60px;font-style:normal;font-weight:100\">info e iscrizioni<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-3-color has-text-color has-medium-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:100\">MODALITA\u2019 DI ISCRIZIONE<\/p>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-3-color has-text-color wp-block-paragraph\" style=\"font-size:18px;font-style:normal;font-weight:100\">Per iscriversi \u00e8 necessario richiedere il modulo di partecipazione, inviando una email a: <br>planasailing@gmail.com<\/p>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-3-color has-text-color wp-block-paragraph\" style=\"font-size:18px;font-style:normal;font-weight:100\">Contestualmente alla sottoscrizione del modulo di partecipazione, che dovr\u00e0 ritornarci compilato e firmato in ogni sua parte, sempre tramite email, \u00e8 necessario effettuare il saldo della quota tramite bonifico bancario intestato a:<br>PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L. IT94K0311104005000000000505<br><\/p>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-3-color has-text-color has-medium-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:100\">INFORMAZIONI<\/p>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-3-color has-text-color wp-block-paragraph\" style=\"font-size:18px;font-style:normal;font-weight:100\">Per info circa modalit\u00e0 di iscrizione, programma, modulo di partecipazione, \u00e8 possibile contattare la Segreteria Organizzativa al numero: (+39) 338 2531249 dal lunedi al venerdi, ore 18.00 alle ore 21.00; il sabato e domenica dalle ore 9.00 alle ore 18.00.<\/p>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-3-color has-text-color wp-block-paragraph\" style=\"font-size:18px;font-style:normal;font-weight:100\">E\u2019 possibile contattare la Segreteria Organizzativa anche tramite WhatsApp al numero (+39) 338 2531249.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MODALITA\u2019 DI ISCRIZIONE Per iscriversi \u00e8 necessario richiedere il modulo di partecipazione, inviando una email a: planasailing@gmail.com Contestualmente alla sottoscrizione del modulo di partecipazione, che dovr\u00e0 ritornarci compilato e firmato&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-391","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>info e iscrizioni - planasailing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"info e iscrizioni - planasailing\" \/>\n<meta property=\"og:description\" content=\"MODALITA\u2019 DI ISCRIZIONE Per iscriversi \u00e8 necessario richiedere il modulo di partecipazione, inviando una email a: planasailing@gmail.com Contestualmente alla sottoscrizione del modulo di partecipazione, che dovr\u00e0 ritornarci compilato e firmato...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/\" \/>\n<meta property=\"og:site_name\" content=\"planasailing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/planasailing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-08T06:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/info-e-iscrizioni\\\/\",\"url\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/info-e-iscrizioni\\\/\",\"name\":\"info e iscrizioni - planasailing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/info-e-iscrizioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/info-e-iscrizioni\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/407c7-30.jpg\",\"datePublished\":\"2022-08-06T16:28:05+00:00\",\"dateModified\":\"2022-08-08T06:38:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/info-e-iscrizioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/planasailing.com\\\/index.php\\\/info-e-iscrizioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/info-e-iscrizioni\\\/#primaryimage\",\"url\":\"http:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/407c7-30.jpg\",\"contentUrl\":\"http:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/407c7-30.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/index.php\\\/info-e-iscrizioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/planasailing.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"info e iscrizioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/#website\",\"url\":\"https:\\\/\\\/planasailing.com\\\/\",\"name\":\"planasailing\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/planasailing.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/#organization\",\"name\":\"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L.\",\"url\":\"https:\\\/\\\/planasailing.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/planasailing.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-9da7b-logo_plana_sailing.jpeg\",\"contentUrl\":\"https:\\\/\\\/planasailing.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-9da7b-logo_plana_sailing.jpeg\",\"width\":512,\"height\":204,\"caption\":\"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/planasailing.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/planasailing\\\/\",\"https:\\\/\\\/www.instagram.com\\\/planasailing\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"info e iscrizioni - planasailing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/","og_locale":"it_IT","og_type":"article","og_title":"info e iscrizioni - planasailing","og_description":"MODALITA\u2019 DI ISCRIZIONE Per iscriversi \u00e8 necessario richiedere il modulo di partecipazione, inviando una email a: planasailing@gmail.com Contestualmente alla sottoscrizione del modulo di partecipazione, che dovr\u00e0 ritornarci compilato e firmato...","og_url":"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/","og_site_name":"planasailing","article_publisher":"https:\/\/www.facebook.com\/planasailing\/","article_modified_time":"2022-08-08T06:38:32+00:00","og_image":[{"url":"http:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/","url":"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/","name":"info e iscrizioni - planasailing","isPartOf":{"@id":"https:\/\/planasailing.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/#primaryimage"},"image":{"@id":"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/#primaryimage"},"thumbnailUrl":"http:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30.jpg","datePublished":"2022-08-06T16:28:05+00:00","dateModified":"2022-08-08T06:38:32+00:00","breadcrumb":{"@id":"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/#primaryimage","url":"http:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30.jpg","contentUrl":"http:\/\/planasailing.com\/wp-content\/uploads\/2022\/08\/407c7-30.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/planasailing.com\/index.php\/info-e-iscrizioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/planasailing.com\/"},{"@type":"ListItem","position":2,"name":"info e iscrizioni"}]},{"@type":"WebSite","@id":"https:\/\/planasailing.com\/#website","url":"https:\/\/planasailing.com\/","name":"planasailing","description":"","publisher":{"@id":"https:\/\/planasailing.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/planasailing.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/planasailing.com\/#organization","name":"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L.","url":"https:\/\/planasailing.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/planasailing.com\/#\/schema\/logo\/image\/","url":"https:\/\/planasailing.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-9da7b-logo_plana_sailing.jpeg","contentUrl":"https:\/\/planasailing.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-9da7b-logo_plana_sailing.jpeg","width":512,"height":204,"caption":"PLANA SAILING SOCIETA\u2019 SPORTIVA AR.L."},"image":{"@id":"https:\/\/planasailing.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/planasailing\/","https:\/\/www.instagram.com\/planasailing\/"]}]}},"_links":{"self":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages\/391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/comments?post=391"}],"version-history":[{"count":2,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages\/391\/revisions"}],"predecessor-version":[{"id":472,"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/pages\/391\/revisions\/472"}],"wp:attachment":[{"href":"https:\/\/planasailing.com\/index.php\/wp-json\/wp\/v2\/media?parent=391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}